{"id":79,"count":1,"description":"","link":"https:\/\/www.amiga-lizenz-lps.de\/index.php\/tag\/dgg\/","name":"DGG","slug":"dgg","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.amiga-lizenz-lps.de\/index.php\/wp-json\/wp\/v2\/tags\/79"}],"collection":[{"href":"https:\/\/www.amiga-lizenz-lps.de\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.amiga-lizenz-lps.de\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.amiga-lizenz-lps.de\/index.php\/wp-json\/wp\/v2\/posts?tags=79"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}